{"id":16034,"date":"2023-01-31T18:32:01","date_gmt":"2023-01-31T16:32:01","guid":{"rendered":"http:\/\/klqewmpxo.cyon.link\/?p=16034"},"modified":"2024-07-13T07:32:35","modified_gmt":"2024-07-13T04:32:35","slug":"erstaunliche-tiere-4","status":"publish","type":"post","link":"https:\/\/azalas.de\/de\/erstaunliche-tiere-4\/","title":{"rendered":"Erstaunliche Tiere 4: Nesseltiere"},"content":{"rendered":"<p><big>E<\/big>iner der erstaunlichsten Zelltypen im Tierreich findet sich &#8211; vielleicht \u00fcberraschenderweise &#8211; bei Tieren, die man auf ersten Blick als primitiv und &#8222;niedrig&#8220; ansehen w\u00fcrde, n\u00e4mlich bei den Nesseltieren. Der Stamm der Nesseltiere <em>(Cnidaria)<\/em> umfasst die <a href=\"http:\/\/azalas.de\/seeanemonen\/\">Seeanemonen<\/a>, die <a href=\"http:\/\/azalas.de\/korallen\">Korallen<\/a>, die <a href=\"http:\/\/azalas.de\/hydrozoen\/\">Hydrozoen<\/a>, die <a href=\"http:\/\/azalas.de\/quallen\/\">Schirmquallen<\/a> und die W\u00fcrfelquallen.<\/p>\n<p><big>D<\/big>ie Nesseltiere sind recht einfach aufgebaute Tiere. Sie besitzen \u00fcblicherweise eine sessile Polypen-Generation und eine im Wasser treibende Medusen-Generation (bei manchen Nesseltieren fehlt die Medusen-Generation, bei anderen die Polypen-Generation). Der K\u00f6rper sowohl der Polypen als auch der Medusen besteht im Wesentlichen aus zwei Epithelien, der \u00e4u\u00dferen Epidermis und der inneren Gastrodermis, zwischen denen eine zellfreie St\u00fctzschicht, die Mesogloea mit Kollagenfasern, liegt. Ihre Nahrung, meist kleine Krebschen und andere Angeh\u00f6rige des Planktons, fangen sie mit Tentakeln ein, die entweder klebrig sind oder meist Nesselzellen besitzen, mithilfe derer die Nahrung abget\u00f6tet wird.<\/p>\n<p><big>D<\/big>ie Nesselzellen sind \u00e4u\u00dferst erstaunliche, sehr hochentwickelte Zellen &#8211; vielleicht die kompliziertesten Zellen, die man \u00fcberhaupt im Tierreich findet. In der Nesselzelle liegt (je nach Typus) ein langer aufgerollter Nesselfaden und ein Apparat mit kleinen Stiletten, die explosionsartig hervorgesto\u00dfen werden, wenn der haarartige Sinnesapparat der Zelle ber\u00fchrt wird. Die Stilette durchsto\u00dfen die K\u00f6rperwand des Opfers und der Nesselfaden wird blitzartig hervorgest\u00fclpt, wobei er die in seinem Inneren gespeicherten Gifte freisetzt. Die Entladung der Nesselzelle erfolgt in wenigen Millisekunden, unter extrem hoher Beschleunigung (etwa das 50fache der Beschleunigung einer Gewehrkugel) und ungew\u00f6hnlich hohem Druck. Wie die Zelle diese hohe Beschleunigung erreicht, ist noch nicht abschlie\u00dfend gekl\u00e4rt. Die Gifte der Nesseltiere sind sehr wirksam; einige Arten (manche Quallen) verursachen starke Schmerzen und Schockzust\u00e4nde und k\u00f6nnen auch f\u00fcr den Menschen gef\u00e4hrlich werden. Die Nesselzellen werden von den Nesseltieren f\u00fcr den Beutefang, zur Verteidigung gegen Fressfeinde und zur Abwehr von Raumkonkurrenten verwendet.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/azalas.de\/wp-content\/uploads\/photos\/naxos\/fauna\/sea_anemones\/aiptasia_mutabilis-1.jpg\" alt=\"Siebanemone\" \/><br \/>\n<small>Im flachen Wasser um Naxos treten mehrere Arten an Seeanemonen auf, hier die Siebanemone <em>(Aiptasia mutabilis)<\/em>. Wenn man eine Siebanemone mit blo\u00dfer Haut ber\u00fchrt, verursacht sie eine Nesselung \u00e4hnlich wie von einer Brennnessel, d.h. ihre Nesselzellen k\u00f6nnen die menschliche Haut durchsto\u00dfen, sind aber nicht gef\u00e4hrlich.<\/small><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/azalas.de\/wp-content\/uploads\/photos\/naxos\/fauna\/hydrozoa\/kirchenpaueria_spec-2.jpg\" alt=\"Kirchenpaueria spec.\" \/><br \/>\n<small>Wesentlich schwerer zu entdecken sind die zarten Hydrozoen, hier vermutlich Angeh\u00f6rige der Gattung <em>Kirchenpaueria<\/em>. Die Polypen vieler Hydrozoen bilden kleine federf\u00f6rmige Kolonien. Die winzigen Polypen einer Kolonie sind durch &#8222;Leitungsbahnen&#8220; direkt miteinander verbunden. Sie sitzen je in einer kleinen Kapsel, in die die mikroskopisch kleinen Tentakel zur\u00fcckgezogen werden k\u00f6nnen. Zwischen gr\u00f6\u00dferen Polypen, die der Nahrungsaufnahme dienen, sitzen bei dieser Gattung kleinere, mit besonders vielen Nesselzellen ausgestattete Wehrpolypen.<\/small><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/azalas.de\/wp-content\/uploads\/photos\/naxos\/fauna\/jellyfish\/pelagia_noctiluca-3.jpg\" alt=\"Leuchtqualle, Pelagia noctiluca\" border=\"0\" \/><br \/>\n<small>Die Nesselzellen der Leuchtqualle <em>(Pelagia noctiluca)<\/em> sitzen an bis zu 1 m langen, sehr d\u00fcnnen und schwer zu sehenden Nesself\u00e4den, die vom Rand des Schirmes herabh\u00e4ngen.<\/small><\/p>\n<p><big>O<\/big>bwohl die Nesseltiere mittels ihrer Nesselzellen die meisten Fressfeinde wirkungsvoll abwehren k\u00f6nnen, gibt es einige Tiere, die sich auf Nesseltiere als Nahrung spezialisiert haben, und denen die Nesselzellen nicht schaden, so zum Beispiel die <a href=\"http:\/\/azalas.de\/unechte-karettschildkroete\/\">Unechte Karettschildkr\u00f6te<\/a>. G\u00e4nzlich erstaunlich ist schlie\u00dflich ein Trick, den manche Meeres-Nacktschnecken und Rippenquallen anwenden, die ausschlie\u00dflich Nesseltiere fressen: Sie verdauen die (noch unreifen) Nesselzellen ihrer Beutetiere nicht, sondern nehmen sie unbesch\u00e4digt auf und bauen sie in ihre eigenen Gewebe ein, so dass sie sie selbst zur Feindabwehr verwenden k\u00f6nnen.<\/p>\n<p>mehr Informationen und Abbildungen zu den faszinierenden Nesselzellen findet man in diesen Artikeln:<\/p>\n<ul>\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Nesselzelle\">Nesselzelle bei Wikipedia<\/a><\/li>\n<li><a href=\"https:\/\/www.koralle-magazin.de\/reefmix\/136-allzweckwaffe-nesselzelle\">Allzweckwaffe Nesselzelle im Koralle-Magazin<\/a><\/li>\n<\/ul>\n<p>siehe auch: <\/p>\n<ul>\n<li><a href=\"http:\/\/azalas.de\/seeanemonen\/\">Seeanemonen<\/a><\/li>\n<li><a href=\"http:\/\/azalas.de\/hydrozoen\/\">Hydrozoen<\/a><\/li>\n<li><a href=\"http:\/\/azalas.de\/quallen\/\">Quallen<\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/azalas.de\/inhaltsverzeichnis\/\">Zum Inhaltsverzeichnis<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einer der erstaunlichsten Zelltypen im Tierreich findet sich &#8211; vielleicht \u00fcberraschenderweise &#8211; bei Tieren, die man auf ersten Blick als primitiv und &#8222;niedrig&#8220; ansehen w\u00fcrde, n\u00e4mlich bei den Nesseltieren. Der Stamm der Nesseltiere (Cnidaria) umfasst die Seeanemonen, die Korallen, die Hydrozoen, die Schirmquallen und die W\u00fcrfelquallen. Die Nesseltiere sind recht einfach aufgebaute Tiere. Sie besitzen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,1090,11,22],"tags":[1135,1050,1134,1049,92],"class_list":["post-16034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles-aus-azalas","category-erstaunliche-tiere","category-natur","category-tiere","tag-hydrozoen","tag-nesseltiere","tag-nesselzellen","tag-quallen","tag-seeanemonen"],"_links":{"self":[{"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/posts\/16034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/comments?post=16034"}],"version-history":[{"count":10,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/posts\/16034\/revisions"}],"predecessor-version":[{"id":67563,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/posts\/16034\/revisions\/67563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/media\/60450"}],"wp:attachment":[{"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/media?parent=16034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/categories?post=16034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azalas.de\/de\/wp-json\/wp\/v2\/tags?post=16034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}